{"id":157,"count":11,"description":"","link":"https:\/\/clickclack.com\/nz\/blog\/category\/entertainment\/","name":"Entertainment","slug":"entertainment","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entertainment Archives - ClickClack New Zealand<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clickclack.com\/nz\/blog\/category\/entertainment\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entertainment Archives - ClickClack New Zealand\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clickclack.com\/nz\/blog\/category\/entertainment\/\" \/>\n<meta property=\"og:site_name\" content=\"ClickClack New Zealand\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/clickclack.com\\\/blog\\\/category\\\/entertainment\\\/\",\"url\":\"https:\\\/\\\/clickclack.com\\\/blog\\\/category\\\/entertainment\\\/\",\"name\":\"Entertainment Archives - ClickClack New Zealand\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clickclack.com\\\/nz\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clickclack.com\\\/blog\\\/category\\\/entertainment\\\/#breadcrumb\"},\"inLanguage\":\"en-NZ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clickclack.com\\\/blog\\\/category\\\/entertainment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clickclack.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entertainment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clickclack.com\\\/nz\\\/#website\",\"url\":\"https:\\\/\\\/clickclack.com\\\/nz\\\/\",\"name\":\"ClickClack New Zealand\",\"description\":\"ClickClack\u00ae is an iconic New Zealand company dedicated to producing stylish and incredibly helpful kitchenware.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clickclack.com\\\/nz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-NZ\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entertainment Archives - ClickClack New Zealand","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clickclack.com\/nz\/blog\/category\/entertainment\/","og_locale":"en_US","og_type":"article","og_title":"Entertainment Archives - ClickClack New Zealand","og_url":"https:\/\/clickclack.com\/nz\/blog\/category\/entertainment\/","og_site_name":"ClickClack New Zealand","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/clickclack.com\/blog\/category\/entertainment\/","url":"https:\/\/clickclack.com\/blog\/category\/entertainment\/","name":"Entertainment Archives - ClickClack New Zealand","isPartOf":{"@id":"https:\/\/clickclack.com\/nz\/#website"},"breadcrumb":{"@id":"https:\/\/clickclack.com\/blog\/category\/entertainment\/#breadcrumb"},"inLanguage":"en-NZ"},{"@type":"BreadcrumbList","@id":"https:\/\/clickclack.com\/blog\/category\/entertainment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clickclack.com\/"},{"@type":"ListItem","position":2,"name":"Entertainment"}]},{"@type":"WebSite","@id":"https:\/\/clickclack.com\/nz\/#website","url":"https:\/\/clickclack.com\/nz\/","name":"ClickClack New Zealand","description":"ClickClack\u00ae is an iconic New Zealand company dedicated to producing stylish and incredibly helpful kitchenware.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clickclack.com\/nz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-NZ"}]}},"_links":{"self":[{"href":"https:\/\/clickclack.com\/nz\/wp-json\/wp\/v2\/categories\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clickclack.com\/nz\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/clickclack.com\/nz\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/clickclack.com\/nz\/wp-json\/wp\/v2\/posts?categories=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}